{"id":306,"count":1,"description":"","link":"https:\/\/ibcparts.eu\/nl\/kategorije\/ibc-verloopstukken-en-connectoren\/dh-63-mm-buitendraad\/","name":"DH 63 mm (buitendraad)","slug":"dh-63-mm-zunanji-navoj","taxonomy":"product_cat","parent":170,"meta":[],"menu_order":10,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DH 63 mm (zunanji navoj) Archives | IBCparts.eu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibcparts.eu\/nl\/kategorien\/ibc-reduzierungen-und-anschlusse\/dh-63-mm-ausengewinde\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DH 63 mm (zunanji navoj) Archives | IBCparts.eu\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibcparts.eu\/nl\/kategorien\/ibc-reduzierungen-und-anschlusse\/dh-63-mm-ausengewinde\/\" \/>\n<meta property=\"og:site_name\" content=\"IBCparts.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/ibcparts.eu\/de\/kategorien\/ibc-reduzierungen-und-anschlusse\/dh-63-mm-ausengewinde\/\",\"url\":\"https:\/\/ibcparts.eu\/de\/kategorien\/ibc-reduzierungen-und-anschlusse\/dh-63-mm-ausengewinde\/\",\"name\":\"DH 63 mm (zunanji navoj) Archives | IBCparts.eu\",\"isPartOf\":{\"@id\":\"https:\/\/ibcparts.eu\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/ibcparts.eu\/de\/kategorien\/ibc-reduzierungen-und-anschlusse\/dh-63-mm-ausengewinde\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ibcparts.eu\/de\/kategorien\/ibc-reduzierungen-und-anschlusse\/dh-63-mm-ausengewinde\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ibcparts.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reducirji, priklju\u010dki, adapterji za IBC\",\"item\":\"https:\/\/ibcparts.eu\/hr\/rubrike\/ibc-redukcije-i-prikljucci\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DH 63 mm (zunanji navoj)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ibcparts.eu\/#website\",\"url\":\"https:\/\/ibcparts.eu\/\",\"name\":\"IBCparts.eu\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/ibcparts.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ibcparts.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ibcparts.eu\/#organization\",\"name\":\"IBCparts\",\"url\":\"https:\/\/ibcparts.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/ibcparts.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ibcparts.eu\/wp-content\/uploads\/2021\/10\/Footer-Logo.png\",\"contentUrl\":\"https:\/\/ibcparts.eu\/wp-content\/uploads\/2021\/10\/Footer-Logo.png\",\"width\":1992,\"height\":772,\"caption\":\"IBCparts\"},\"image\":{\"@id\":\"https:\/\/ibcparts.eu\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DH 63 mm (zunanji navoj) Archives | IBCparts.eu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibcparts.eu\/nl\/kategorien\/ibc-reduzierungen-und-anschlusse\/dh-63-mm-ausengewinde\/","og_locale":"nl_NL","og_type":"article","og_title":"DH 63 mm (zunanji navoj) Archives | IBCparts.eu","og_url":"https:\/\/ibcparts.eu\/nl\/kategorien\/ibc-reduzierungen-und-anschlusse\/dh-63-mm-ausengewinde\/","og_site_name":"IBCparts.eu","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ibcparts.eu\/de\/kategorien\/ibc-reduzierungen-und-anschlusse\/dh-63-mm-ausengewinde\/","url":"https:\/\/ibcparts.eu\/de\/kategorien\/ibc-reduzierungen-und-anschlusse\/dh-63-mm-ausengewinde\/","name":"DH 63 mm (zunanji navoj) Archives | IBCparts.eu","isPartOf":{"@id":"https:\/\/ibcparts.eu\/#website"},"breadcrumb":{"@id":"https:\/\/ibcparts.eu\/de\/kategorien\/ibc-reduzierungen-und-anschlusse\/dh-63-mm-ausengewinde\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/ibcparts.eu\/de\/kategorien\/ibc-reduzierungen-und-anschlusse\/dh-63-mm-ausengewinde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ibcparts.eu\/"},{"@type":"ListItem","position":2,"name":"Reducirji, priklju\u010dki, adapterji za IBC","item":"https:\/\/ibcparts.eu\/hr\/rubrike\/ibc-redukcije-i-prikljucci\/"},{"@type":"ListItem","position":3,"name":"DH 63 mm (zunanji navoj)"}]},{"@type":"WebSite","@id":"https:\/\/ibcparts.eu\/#website","url":"https:\/\/ibcparts.eu\/","name":"IBCparts.eu","description":"","publisher":{"@id":"https:\/\/ibcparts.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibcparts.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/ibcparts.eu\/#organization","name":"IBCparts","url":"https:\/\/ibcparts.eu\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/ibcparts.eu\/#\/schema\/logo\/image\/","url":"https:\/\/ibcparts.eu\/wp-content\/uploads\/2021\/10\/Footer-Logo.png","contentUrl":"https:\/\/ibcparts.eu\/wp-content\/uploads\/2021\/10\/Footer-Logo.png","width":1992,"height":772,"caption":"IBCparts"},"image":{"@id":"https:\/\/ibcparts.eu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ibcparts.eu\/nl\/wp-json\/wp\/v2\/product_cat\/306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibcparts.eu\/nl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/ibcparts.eu\/nl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/ibcparts.eu\/nl\/wp-json\/wp\/v2\/product_cat\/170"}],"wp:post_type":[{"href":"https:\/\/ibcparts.eu\/nl\/wp-json\/wp\/v2\/product?product_cat=306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}